{"id":599,"date":"2014-07-10T00:02:08","date_gmt":"2014-07-09T22:02:08","guid":{"rendered":"http:\/\/wuerenblicker.ch\/wp\/wp-content\/uploads\/2014\/07\/Altwiesenstrasse.jpg"},"modified":"2014-07-10T00:02:08","modified_gmt":"2014-07-09T22:02:08","slug":"altwiesenstrasse","status":"inherit","type":"attachment","link":"https:\/\/wuerenblicker.ch\/wp\/altwiesenstrasse\/","title":{"rendered":"Altwiesenstrasse"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-599","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/wuerenblicker.ch\/wp\/wp-content\/uploads\/2014\/07\/Altwiesenstrasse.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/wuerenblicker.ch\/wp\/wp-content\/uploads\/2014\/07\/Altwiesenstrasse-300x210.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wuerenblicker.ch\/wp\/wp-content\/uploads\/2014\/07\/Altwiesenstrasse-300x210.jpg 300w, https:\/\/wuerenblicker.ch\/wp\/wp-content\/uploads\/2014\/07\/Altwiesenstrasse.jpg 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div class='watch-action'><div class='watch-position align-right'><div class='action-like'><a class='lbg-style1 like-599 jlk' href='javascript:void(0)' data-task='like' data-post_id='599' data-nonce='427c496796' rel='nofollow'><img class='wti-pixel' src='https:\/\/wuerenblicker.ch\/wp\/wp-content\/plugins\/wti-like-post\/images\/pixel.gif' title='Like' \/><span class='lc-599 lc'>+14<\/span><\/a><\/div><div class='action-unlike'><a class='unlbg-style1 unlike-599 jlk' href='javascript:void(0)' data-task='unlike' data-post_id='599' data-nonce='427c496796' rel='nofollow'><img class='wti-pixel' src='https:\/\/wuerenblicker.ch\/wp\/wp-content\/plugins\/wti-like-post\/images\/pixel.gif' title='Unlike' \/><span class='unlc-599 unlc'>-4<\/span><\/a><\/div> <\/div> <div class='status-599 status align-right'><\/div><\/div><div class='wti-clear'><\/div>"},"caption":{"rendered":"<p>Altwiesenstrasse<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":350,"height":246,"file":"2014\/07\/Altwiesenstrasse.jpg","sizes":{"thumbnail":{"file":"Altwiesenstrasse-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/wuerenblicker.ch\/wp\/wp-content\/uploads\/2014\/07\/Altwiesenstrasse-150x150.jpg"},"medium":{"file":"Altwiesenstrasse-300x210.jpg","width":300,"height":210,"mime_type":"image\/jpeg","source_url":"https:\/\/wuerenblicker.ch\/wp\/wp-content\/uploads\/2014\/07\/Altwiesenstrasse-300x210.jpg"},"post-thumbnail":{"file":"Altwiesenstrasse-350x198.jpg","width":350,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/wuerenblicker.ch\/wp\/wp-content\/uploads\/2014\/07\/Altwiesenstrasse-350x198.jpg"},"full":{"file":"Altwiesenstrasse.jpg","width":350,"height":246,"mime_type":"image\/jpeg","source_url":"https:\/\/wuerenblicker.ch\/wp\/wp-content\/uploads\/2014\/07\/Altwiesenstrasse.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":null,"source_url":"https:\/\/wuerenblicker.ch\/wp\/wp-content\/uploads\/2014\/07\/Altwiesenstrasse.jpg","_links":{"self":[{"href":"https:\/\/wuerenblicker.ch\/wp\/wp-json\/wp\/v2\/media\/599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wuerenblicker.ch\/wp\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/wuerenblicker.ch\/wp\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/wuerenblicker.ch\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wuerenblicker.ch\/wp\/wp-json\/wp\/v2\/comments?post=599"}]}}